{"id":934,"date":"2010-05-25T14:43:28","date_gmt":"2010-05-25T13:43:28","guid":{"rendered":"https:\/\/blog.iese.edu\/martinezabascal\/?p=934"},"modified":"2011-09-16T12:31:33","modified_gmt":"2011-09-16T11:31:33","slug":"el-coste-de-actuar-tarde","status":"publish","type":"post","link":"https:\/\/blog.iese.edu\/martinezabascal\/2010\/05\/25\/el-coste-de-actuar-tarde\/","title":{"rendered":"El coste de actuar tarde"},"content":{"rendered":"<p>Publicado en <em><a href=\"http:\/\/www.expansion.com\/\" target=\"_blank\">Expansi\u00f3n<\/a><\/em> el 25 de mayo de 2010.<\/p>\n<p>Los recortes de gasto por parte del gobierno han llegado tarde, muy tarde y por tanto son m\u00e1s dolorosos y m\u00e1s costosos de lo que hubieran sido de haber tomado las medidas de ahorro hace dos a\u00f1os. He aqu\u00ed algunos ejemplos.<\/p>\n<p>El recorte en infraestructuras es de unos 6.000 millones de euros. Es sabido que la mayor\u00eda de infraestructuras, casi siempre de transporte, hacen que la econom\u00eda espa\u00f1ola sea m\u00e1s competitiva ya que el empresario se ahorra dinero en transporte y puede enviar sus productos m\u00e1s lejos. Buena cosa. Ahora esas inversiones, se aplazan. No hay dinero. Lo entiendo. Pero&#8230; gran pero: El a\u00f1o 2009, y en plena crisis nos gastamos 8.000 o m\u00e1s bien 9.000 millones en el famoso plan E para arreglar aceras de nuestros pueblos y ciudades. Algunos dir\u00e1n que no s\u00f3lo eran aceras, parques y jardines, pero la realidad es la que todos los espa\u00f1oles hemos visto: aceras!!! \u00bfMejora la competitividad del pa\u00eds por tener aceras m\u00e1s anchas? Es obvio que no.<\/p>\n<p>Me comenta un taxista al respecto. \u201cSi me ampl\u00edan una gran avenida y la hacen m\u00e1s r\u00e1pida para dar fluidez al tr\u00e1fico, o hacen un carretera radial, yo puedo hacer tres carreras en un hora en lugar de dos. Si me ampl\u00edan la acera, pasear\u00e9 m\u00e1s tranquilo, y me vendr\u00e1 bien por que habr\u00e9 colgado el taxi por falta de negocio\u201d. Una acera amplia no aumenta la productividad, una nueva avenida o v\u00eda de circulaci\u00f3n r\u00e1pida s\u00ed. No tiene sentido gastarse 8.000 millones en aceras y al a\u00f1o siguiente recortar 6.000 en infraestructuras. Esto es tan evidente que asombra que nadie en el gobierno lo pudiera ver.<\/p>\n<p>Recorte del sueldo de funcionarios. Ahorro estimado, 3.000 millones. Ha causado mucho ruido, pues afecta a mucha gente. Pues bien, s\u00f3lo las subvenciones a los parques solares fueron 2.300 millones en el 2009; casi tanto como el ahorro que se quiere conseguir reduciendo el sueldo de los funcionarios.<\/p>\n<p>El gobierno nos pide sacrificios y lanza un plan de reducci\u00f3n de gastos de 15.000 millones. Pues bien, s\u00f3lo con los dos conceptos anteriores, fotovoltaicas y plan E, nos habr\u00edamos ahorrado 11.000 millones&#8230; que ahora nos vendr\u00edan muy bien. No digo que estoy en contra del plan de ajuste de gastos del gobierno (m\u00e1s vale tarde que nunca). Digo que por hacerlo tarde el plan tiene un coste social y econ\u00f3mico enorme&#8230; por no haber actuado a tiempo. \u00bfNadie en el equipo de gobierno se percat\u00f3?<\/p>\n<p><a href=\"https:\/\/blog.iese.edu\/martinezabascal\/files\/2010\/06\/88.-El-coste-de-actuar-tarde1.pdf\">Art\u00edculo en pdf<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Publicado en Expansi\u00f3n el 25 de mayo de 2010. Los recortes de gasto por parte del gobierno han llegado tarde, muy tarde y por tanto son m\u00e1s dolorosos y m\u00e1s costosos de lo que hubieran sido de haber tomado las medidas de ahorro hace dos a\u00f1os. He aqu\u00ed algunos ejemplos. El recorte en infraestructuras es [&hellip;]<\/p>\n","protected":false},"author":166,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26212],"tags":[16418,16420,16419],"class_list":["post-934","post","type-post","status-publish","format-standard","hentry","category-economia-crisis-economica","tag-inversion-publica","tag-plan-e","tag-politicas-keynesianas"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/blog.iese.edu\/martinezabascal\/wp-json\/wp\/v2\/posts\/934","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.iese.edu\/martinezabascal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.iese.edu\/martinezabascal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.iese.edu\/martinezabascal\/wp-json\/wp\/v2\/users\/166"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.iese.edu\/martinezabascal\/wp-json\/wp\/v2\/comments?post=934"}],"version-history":[{"count":3,"href":"https:\/\/blog.iese.edu\/martinezabascal\/wp-json\/wp\/v2\/posts\/934\/revisions"}],"predecessor-version":[{"id":1564,"href":"https:\/\/blog.iese.edu\/martinezabascal\/wp-json\/wp\/v2\/posts\/934\/revisions\/1564"}],"wp:attachment":[{"href":"https:\/\/blog.iese.edu\/martinezabascal\/wp-json\/wp\/v2\/media?parent=934"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.iese.edu\/martinezabascal\/wp-json\/wp\/v2\/categories?post=934"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.iese.edu\/martinezabascal\/wp-json\/wp\/v2\/tags?post=934"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}